{"id":12086,"date":"2025-01-23T13:16:43","date_gmt":"2025-01-23T12:16:43","guid":{"rendered":"https:\/\/shop.s-line.it\/?post_type=product&#038;p=12086"},"modified":"2025-06-06T11:50:13","modified_gmt":"2025-06-06T09:50:13","slug":"ricariche-multicolor-solo-linea-brillante-scatola-24-pz","status":"publish","type":"product","link":"https:\/\/shop.s-line.it\/fr\/prodotto\/ricariche-multicolor-solo-linea-brillante-scatola-24-pz\/","title":{"rendered":"Ricariche multicolor solo linea brillante (scatola 24 pz.)"},"content":{"rendered":"<p><strong>RICARICHE MULTICOLOR LINEA BRILLANTE<br \/>\n24 PEZZI ROTOLI COLORI ASSORTITI<\/strong><strong><br \/>\nPER DISPENSER TACK-IT NERO, TACK-IT TRASPARENTE E TACK-IT NOTE<br \/>\n<\/strong><\/p>\n<p>Nastro in carta adesiva colorata scrivibile, removibile e riposizionabile. Una volta terminato il rotolo fornito nel dispenser, \u00e8 possibile reintegrarlo con le ricariche disponibili in diversi colori e formati a seconda dell&rsquo;applicatore utilizzato<\/p>\n<p>Dotato di un adesivo removibile molto tenace, si applica a qualsiasi superfice (carta, plastica, metallo, legno, ecc&#8230;) e consente di creare appunti di svariate misure evitando inutili sprechi. La superficie interamente adesiva garantisce un&rsquo;ottima tenuta, una facile rimozione senza residui e la possibilit\u00e0 di attaccare e staccare pi\u00f9 volte il pezzo desiderato senza perderne il potere adesivo.<\/p>\n<p><strong>Composizione colori scatola da 24 pezzi:<\/strong><\/p>\n<ul>\n<li>6 pz. giallo fluo brillante<\/li>\n<li>6 pz. rosa baby brillante<\/li>\n<li>6 pz. verde lime brillante<\/li>\n<li>6 pz. arancio brillante<\/li>\n<\/ul>\n<p>Le ricariche <strong>TACK-IT LINEA BRILLANTE<\/strong> presentano rotoli realizzati interamente con carta <em>wood-free<\/em>, ovvero ottenuta da una polpa priva di legno.<\/p>\n<div>\n<p><em>Caratteristiche tecniche:<\/em><\/p>\n<p><strong>Spessore:<\/strong> 70 g\/m2, in base al colore<br \/>\n<strong>Dimensioni rotolo:<\/strong> 60 mm x 10 m<br \/>\n<strong>Adesivo:<\/strong> removibile acrilico base acqua<br \/>\n<strong>Carta:<\/strong> 100% riciclata<\/p>\n<p>Marca: SL Adhesive &amp; Safety<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p><em>La prima foto presente nella gallery \u00e8 esemplificativa del tipo di imballo multi-color che si ricever\u00e0: i colori presenti nella fornitura sono quelli presentati nelle foto successive alla prima e riportati nella descrizione<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nastro in carta adesiva colorata scrivibile, removibile e riposizionabile. Una volta terminato il rotolo fornito nel dispenser, \u00e8 possibile reintegrarlo con le ricariche disponibili in diversi colori e formati a seconda dell&rsquo;applicatore utilizzato<\/p>\n<p>Dotato di un adesivo removibile molto tenace, si applica a qualsiasi superfice (carta, plastica, metallo, legno, ecc&#8230;) e consente di creare appunti di svariate misure evitando inutili sprechi. La superficie interamente adesiva garantisce un&rsquo;ottima tenuta, una facile rimozione senza residui e la possibilit\u00e0 di attaccare e staccare pi\u00f9 volte il pezzo desiderato senza perderne il potere adesivo.<\/p>\n","protected":false},"featured_media":12389,"template":"","meta":[],"product_brand":[],"product_cat":[231],"product_tag":[496,472,606,605,604],"class_list":["post-12086","product","type-product","status-publish","has-post-thumbnail","product_cat-nastri-ufficio-fr","product_tag-accueil","product_tag-adhesif-amovible","product_tag-bureau","product_tag-ecole","product_tag-ruban-inscriptible","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/shop.s-line.it\/fr\/wp-json\/wp\/v2\/product\/12086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/shop.s-line.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/shop.s-line.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/shop.s-line.it\/fr\/wp-json\/wp\/v2\/media\/12389"}],"wp:attachment":[{"href":"https:\/\/shop.s-line.it\/fr\/wp-json\/wp\/v2\/media?parent=12086"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/shop.s-line.it\/fr\/wp-json\/wp\/v2\/product_brand?post=12086"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/shop.s-line.it\/fr\/wp-json\/wp\/v2\/product_cat?post=12086"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/shop.s-line.it\/fr\/wp-json\/wp\/v2\/product_tag?post=12086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}